{"id":10023,"date":"2023-04-01T14:07:01","date_gmt":"2023-04-01T12:07:01","guid":{"rendered":"https:\/\/www.nrgi.ch\/?p=10023"},"modified":"2023-04-01T14:07:04","modified_gmt":"2023-04-01T12:07:04","slug":"merci-et-a-bientot","status":"publish","type":"post","link":"https:\/\/www.nrgi.ch\/index.php\/2023\/04\/01\/merci-et-a-bientot\/","title":{"rendered":"Merci et \u00e0 bient\u00f4t!"},"content":{"rendered":"\n<p>Notre Madame Neige ne nous aura finalement pas offert le bis tant esp\u00e9r\u00e9. L&rsquo;assaut rageur du 16 janvier aura \u00e9t\u00e9 finalement le seul de tout l&rsquo;hiver. Quelques semaines de bonheur, des journ\u00e9es exceptionnelles, des pistes prises d&rsquo;assaut. Ce fut bien&#8230; mais bien trop court.<\/p>\n\n\n\n<p>Merci chers skieurs! Votre pr\u00e9sence toujours plus nombreuse sur nos pistes nous donne chaque ann\u00e9e du courage pour remettre de l&rsquo;ouvrage sur le m\u00e9tier. Il faut pousser de la neige, peller, retracer&#8230; Qu&rsquo;importe! Vos sourires et vos mercis remplissent nos coeurs.<\/p>\n\n\n\n<p>Merci \u00e9galement \u00e0 l&rsquo;\u00e9quipes des traceurs, aux b\u00e9n\u00e9voles de tous genres, au comit\u00e9. Sans vous rien ne serait possible.<\/p>\n\n\n\n<p>Merci \u00e0 Madame Neige et \u00e0 toute la smala du Gibloux. On vous aime!<\/p>\n\n\n\n<p>Bel \u00e9t\u00e9 \u00e0 tous et rendez-vous \u00e0 la premi\u00e8re crach\u00e9e de neige! Promis, nous serons pr\u00eats!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre Madame Neige ne nous aura finalement pas offert le bis tant esp\u00e9r\u00e9. L&rsquo;assaut rageur du 16 janvier aura \u00e9t\u00e9 finalement le seul de tout l&rsquo;hiver. Quelques semaines de bonheur, des journ\u00e9es exceptionnelles, des pistes prises d&rsquo;assaut. Ce fut bien&#8230; mais bien trop court. Merci chers skieurs! Votre pr\u00e9sence toujours plus nombreuse sur nos pistes nous donne chaque ann\u00e9e du courage pour remettre de l&rsquo;ouvrage sur le m\u00e9tier. Il faut pousser de la neige, peller, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":["post-10023","post","type-post","status-publish","format-standard","hentry","category-info"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/10023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/comments?post=10023"}],"version-history":[{"count":1,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/10023\/revisions"}],"predecessor-version":[{"id":10024,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/10023\/revisions\/10024"}],"wp:attachment":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/media?parent=10023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/categories?post=10023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/tags?post=10023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}