{"id":1667,"date":"2014-03-03T07:02:31","date_gmt":"2014-03-03T06:02:31","guid":{"rendered":"http:\/\/www.buntschu.ch\/nrgi\/?p=1667"},"modified":"2014-03-03T07:02:31","modified_gmt":"2014-03-03T06:02:31","slug":"encore-et-encore-2","status":"publish","type":"post","link":"https:\/\/www.nrgi.ch\/index.php\/2014\/03\/03\/encore-et-encore-2\/","title":{"rendered":"Encore et encore"},"content":{"rendered":"<p>\t\t\t\tPetit \u00e9pisode neigeux ce matin sur le Gibloux.<\/p>\n<p>Tiens tiens&#8230; pour changer. La coquine de Madame Neige ne finit pas de nous surprendre!<\/p>\n<p>La semaine de Carnaval s&rsquo;annonce tr\u00e8s bien pour tous les fondeurs du Gibloux.<\/p>\n<p>Les pistes retrac\u00e9es hier soir sont g\u00e9n\u00e9ralement bonnes. Le secteur le long du Bugnon a \u00e9t\u00e9 trac\u00e9 jusqu&rsquo;\u00e0 la route ainsi que tout le tron\u00e7on des Monts de Riaz qui est excellent.\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Petit \u00e9pisode neigeux ce matin sur le Gibloux. Tiens tiens&#8230; pour changer. La coquine de Madame Neige ne finit pas de nous surprendre! La semaine de Carnaval s&rsquo;annonce tr\u00e8s bien pour tous les fondeurs du Gibloux. Les pistes retrac\u00e9es hier soir sont g\u00e9n\u00e9ralement bonnes. Le secteur le long du Bugnon a \u00e9t\u00e9 trac\u00e9 jusqu&rsquo;\u00e0 la route ainsi que tout le tron\u00e7on des Monts de Riaz qui est excellent.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":["post-1667","post","type-post","status-publish","format-standard","hentry","category-info"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/1667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1667"}],"version-history":[{"count":0,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/1667\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}