{"id":1796,"date":"2014-03-11T06:45:38","date_gmt":"2014-03-11T05:45:38","guid":{"rendered":"http:\/\/www.buntschu.ch\/nrgi\/?p=1796"},"modified":"2014-03-11T06:45:38","modified_gmt":"2014-03-11T05:45:38","slug":"coup-de-chaud","status":"publish","type":"post","link":"https:\/\/www.nrgi.ch\/index.php\/2014\/03\/11\/coup-de-chaud\/","title":{"rendered":"Coup de chaud"},"content":{"rendered":"<p>\t\t\t\tSacr\u00e9 coup de chaud sur le Gibloux depuis quelques jours. La neige transpire! Les oiseaux sont en bikini&#8230; c&rsquo;est un peu l&rsquo;\u00e9t\u00e9 avant l&rsquo;heure.<\/p>\n<p>Malgr\u00e9 tout nous avons retrac\u00e9 10 km hier soir avant le gel de la nuit. En matin\u00e9e les conditions sont bonnes avant l&rsquo;attaque du soleil. Quelques passages ont \u00e9t\u00e9 mis \u00e0 mal par la douceur mais dans l&rsquo;ensemble c&rsquo;est encore bien skiable.\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sacr\u00e9 coup de chaud sur le Gibloux depuis quelques jours. La neige transpire! Les oiseaux sont en bikini&#8230; c&rsquo;est un peu l&rsquo;\u00e9t\u00e9 avant l&rsquo;heure. Malgr\u00e9 tout nous avons retrac\u00e9 10 km hier soir avant le gel de la nuit. En matin\u00e9e les conditions sont bonnes avant l&rsquo;attaque du soleil. Quelques passages ont \u00e9t\u00e9 mis \u00e0 mal par la douceur mais dans l&rsquo;ensemble c&rsquo;est encore bien skiable.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":["post-1796","post","type-post","status-publish","format-standard","hentry","category-info"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/1796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1796"}],"version-history":[{"count":0,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/1796\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}