{"id":4810,"date":"2016-03-20T06:28:21","date_gmt":"2016-03-20T05:28:21","guid":{"rendered":"http:\/\/www.nrgi.ch\/?p=4810"},"modified":"2016-03-20T06:28:21","modified_gmt":"2016-03-20T05:28:21","slug":"si-si-ca-passe-encore","status":"publish","type":"post","link":"https:\/\/www.nrgi.ch\/index.php\/2016\/03\/20\/si-si-ca-passe-encore\/","title":{"rendered":"Si si, \u00e7a passe encore!"},"content":{"rendered":"<p>\t\t\t\tSuperbe journ\u00e9e de soleil hier sur le Gibloux avec des temp\u00e9ratures quasi printani\u00e8res.<\/p>\n<p>Notre bouclette bouclinette r\u00e9siste toujours au printemps naissant. Elle est encore excellente et toute fra\u00eeche trac\u00e9e.<\/p>\n<p>Profitez des derni\u00e8res journ\u00e9es de ski sur le Gibloux. Celui-ci sera bient\u00f4t rendu aux oiseaux et \u00e0 l&rsquo;herbe fra\u00eeche.<\/p>\n<p>D&rsquo;ailleurs Madame Neige du Gibloux se r\u00e9jouit de passer son premier \u00e9t\u00e9 sur sa petite colline. Elle pourra enfin faire connaissance des g\u00e9nisses et des petites fleurs.<\/p>\n<p>Bon ski\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Superbe journ\u00e9e de soleil hier sur le Gibloux avec des temp\u00e9ratures quasi printani\u00e8res. Notre bouclette bouclinette r\u00e9siste toujours au printemps naissant. Elle est encore excellente et toute fra\u00eeche trac\u00e9e. Profitez des derni\u00e8res journ\u00e9es de ski sur le Gibloux. Celui-ci sera bient\u00f4t rendu aux oiseaux et \u00e0 l&rsquo;herbe fra\u00eeche. D&rsquo;ailleurs Madame Neige du Gibloux se r\u00e9jouit de passer son premier \u00e9t\u00e9 sur sa petite colline. Elle pourra enfin faire connaissance des g\u00e9nisses et des petites fleurs. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":["post-4810","post","type-post","status-publish","format-standard","hentry","category-info"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/4810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/comments?post=4810"}],"version-history":[{"count":0,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/4810\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/media?parent=4810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/categories?post=4810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/tags?post=4810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}