{"id":8891,"date":"2021-03-16T09:12:39","date_gmt":"2021-03-16T08:12:39","guid":{"rendered":"https:\/\/www.nrgi.ch\/?p=8891"},"modified":"2021-03-16T09:12:42","modified_gmt":"2021-03-16T08:12:42","slug":"on-trace-yes","status":"publish","type":"post","link":"https:\/\/www.nrgi.ch\/index.php\/2021\/03\/16\/on-trace-yes\/","title":{"rendered":"On trace???? YES!"},"content":{"rendered":"\n<p>Raubac la baraque, \u00e9moustill\u00e9 par les chutes de neige de cette nuit nous offre une petite boucle in\u00e9dite sur notre Gibloux. <\/p>\n\n\n\n<p>Alors que samedi dernier notre valeureuse \u00e9quipe de b\u00e9n\u00e9voles avait rang\u00e9 tout le mat\u00e9riel, voil\u00e0 que Madame Neige a d\u00e9cid\u00e9 de nous offrir un tango neigeux dont elle seule a le secret.<\/p>\n\n\n\n<p>On chausse les lattes, on dit merci la vie et on dit&#8230;<\/p>\n\n\n\n<p>YOU HOU HOU<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Raubac la baraque, \u00e9moustill\u00e9 par les chutes de neige de cette nuit nous offre une petite boucle in\u00e9dite sur notre Gibloux. Alors que samedi dernier notre valeureuse \u00e9quipe de b\u00e9n\u00e9voles avait rang\u00e9 tout le mat\u00e9riel, voil\u00e0 que Madame Neige a d\u00e9cid\u00e9 de nous offrir un tango neigeux dont elle seule a le secret. On chausse les lattes, on dit merci la vie et on dit&#8230; YOU HOU HOU<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":["post-8891","post","type-post","status-publish","format-standard","hentry","category-info"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/8891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/comments?post=8891"}],"version-history":[{"count":1,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/8891\/revisions"}],"predecessor-version":[{"id":8892,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/8891\/revisions\/8892"}],"wp:attachment":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/media?parent=8891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/categories?post=8891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/tags?post=8891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}