{"id":9016,"date":"2021-11-29T16:14:34","date_gmt":"2021-11-29T15:14:34","guid":{"rendered":"https:\/\/www.nrgi.ch\/?p=9016"},"modified":"2021-11-29T16:14:37","modified_gmt":"2021-11-29T15:14:37","slug":"le-premier-you-hou-hou-de-lhiver","status":"publish","type":"post","link":"https:\/\/www.nrgi.ch\/index.php\/2021\/11\/29\/le-premier-you-hou-hou-de-lhiver\/","title":{"rendered":"Le premier you hou hou de l&rsquo;hiver"},"content":{"rendered":"\n<p>Amis du Gibloux bonjour. Premiers frimas de l&rsquo;hiver. Premier skieur sur nos pistes. Emotion&#8230; On esp\u00e8re que c&rsquo;est le d\u00e9but d&rsquo;une longue saison. Notre chef des pistes Raubac la baraque a os\u00e9 le pas. Premier passage sur le chalet neuf ainsi que la HH. C&rsquo;est blanc, c&rsquo;est beau, \u00e7a fait du bien. Madame Neige, on reprend volontiers une tourn\u00e9e!<\/p>\n\n\n\n<p>You hou hou!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amis du Gibloux bonjour. Premiers frimas de l&rsquo;hiver. Premier skieur sur nos pistes. Emotion&#8230; On esp\u00e8re que c&rsquo;est le d\u00e9but d&rsquo;une longue saison. Notre chef des pistes Raubac la baraque a os\u00e9 le pas. Premier passage sur le chalet neuf ainsi que la HH. C&rsquo;est blanc, c&rsquo;est beau, \u00e7a fait du bien. Madame Neige, on reprend volontiers une tourn\u00e9e! You hou hou!<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"zakra_page_container_layout":"customizer","zakra_page_sidebar_layout":"customizer","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[26],"tags":[],"class_list":["post-9016","post","type-post","status-publish","format-standard","hentry","category-info"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/9016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/comments?post=9016"}],"version-history":[{"count":1,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/9016\/revisions"}],"predecessor-version":[{"id":9017,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/posts\/9016\/revisions\/9017"}],"wp:attachment":[{"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/media?parent=9016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/categories?post=9016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nrgi.ch\/index.php\/wp-json\/wp\/v2\/tags?post=9016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}